{"id":15036,"date":"2023-04-13T14:45:41","date_gmt":"2023-04-13T14:45:49","guid":{"rendered":"https:\/\/mariblum.de\/?post_type=product&#038;p=15036"},"modified":"2025-04-21T12:29:17","modified_gmt":"2025-04-21T12:29:17","slug":"campo-di-lavanda-ring-sling-in-lino","status":"publish","type":"product","link":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/","title":{"rendered":"Campo di Lavanda &#8211; Ring Sling in lino"},"content":{"rendered":"<h3>Campo di Lavanda Ring Sling in lino<\/h3>\n<p style=\"text-align: justify;\">La nostra bellissima imbragatura ad anello &#8220;Campo di Lavanda&#8221; \u00e8 realizzata in 100% lino biologico e ha un aspetto simile e allo stesso tempo non simile alla sorella maggiore &#8220;Viola&#8221;. Le piante rosa e viola sono state distribuite in modo diverso su Lavendelfeld, creando una sfumatura di colore molto armoniosa.<\/p>\n\n  <div class=\"banner has-hover\" id=\"banner-571624019\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2021\/01\/lila-tragetuch-baby-schlafen.jpg\" class=\"bg attachment-medium_large size-medium_large\" alt=\"lila-tragetuch-baby-schlafen\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1440964140\" class=\"text-box banner-layer x5 md-x5 lg-x5 y95 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text box-shadow-3\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Viola<\/strong><\/h2>\n<h3>Imbracatura<\/h3>\n<p align=\"justify\">Il viola \u00e8 un colore che si trova raramente in natura. Per questo motivo attira facilmente l&#8217;attenzione visiva.<\/p>\n<a href=\"https:\/\/mariblum.de\/it\/produkt\/viola-fascia-porta-bebe\/\" class=\"button primary\" style=\"border-radius:25px;\">\n\t\t<span>all&#039;imbracatura<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1440964140 .text-box-content {\n  background-color: rgb(255, 255, 255);\n  border-radius: 22px;\n  font-size: 49%;\n}\n#text-box-1440964140 .text-inner {\n  padding: 30px 30px 30px 30px;\n}\n#text-box-1440964140 {\n  width: 89%;\n}\n@media (min-width:550px) {\n  #text-box-1440964140 {\n    width: 36%;\n  }\n  #text-box-1440964140 .text-box-content {\n    font-size: 100%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1440964140 {\n    width: 27%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-571624019 {\n  padding-top: 400px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-571624019 .overlay {\n  background-color: rgba(190, 190, 190, 0.2);\n}\n#banner-571624019 .banner-bg img {\n  object-position: 11% 58%;\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"gap-448625498\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-448625498 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-646631569\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-646631569 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row\"  id=\"row-686120028\">\r\n\r\n\n\t<div id=\"col-1082091543\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n<p style=\"text-align: justify;\">Tutti i nostri marsupi ad anelle sono sottili e molto stabili. Cos\u00ec \u00e8 molto facile metterli in tensione. Si adattano quindi perfettamente a te e al tuo bimbo, quasi come una seconda pelle. Il ring sling in Lino \u00e8 gi\u00e0 molto morbido, ma si ammorbidisce ancora quando viene indossato e legato. Dato che il lino \u00e8 una fibra molto forte, il imbracatura mantiene a lungo il suo piacevole comfort (<a href=\"https:\/\/mariblum.de\/it\/lino-vantaggi-dei-fascia-o-dei-marsupi-ad-anello\/\">scopri di pi\u00f9 sul lino qui<\/a>). Questo imbracatura sar\u00e0 un compagno fedele anche su lunghi tragitti. Quando non ne hai pi\u00f9 bisogno puoi riporlo comodamente nella borsa.<\/p>\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-2044399604\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n  <div class=\"banner has-hover\" id=\"banner-58727901\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/10\/ring-sling-tragetuch-aus-leinen-luxus-edel.jpg\" class=\"bg attachment-medium_large size-medium_large\" alt=\"campo-di-nebbia-ring-sling-in-lino\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \r\n\r\n   <div id=\"text-box-2080982943\" class=\"text-box banner-layer x5 md-x5 lg-x5 y50 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text box-shadow-3\">\n              \n              <div class=\"text-inner text-left\">\n                  \r\n<h2 class=\"uppercase\" align=\"center\"><strong>Lino<\/strong><\/h2>\r\n<h3 align=\"center\">Ring Sling<\/h3>\r\n<p align=\"center\">Una ring sling di lino ha molti vantaggi. Leggete il nostro blog per scoprire quali sono e come supportano voi e il vostro bambino.<\/p>\r\n<center><a href=\"https:\/\/mariblum.de\/it\/lino-vantaggi-dei-fascia-o-dei-marsupi-ad-anello\/\" class=\"button primary\" style=\"border-radius:25px;\">\n\t\t<span>pi\u00fa<\/span>\n\t<\/a>\n<\/center>\r\n\r\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-2080982943 .text-box-content {\n  background-color: rgb(255, 255, 255);\n  border-radius: 55px;\n  font-size: 100%;\n}\n#text-box-2080982943 .text-inner {\n  padding: 30px 30px 30px 30px;\n}\n#text-box-2080982943 {\n  width: 60%;\n}\n@media (min-width:550px) {\n  #text-box-2080982943 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \r\n\r\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-58727901 {\n  padding-top: 400px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-58727901 .overlay {\n  background-color: rgba(190, 190, 190, 0.2);\n}\n#banner-58727901 .banner-bg img {\n  object-position: 28% 33%;\n}\n<\/style>\n  <\/div>\n\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\n<div class=\"row\"  id=\"row-904635204\">\r\n\r\n\n\t<div id=\"col-1408723370\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\nNote:\r\n\r\nLa fascia ad anelli in lino \u00e8 relativamente sottile, molto morbida e molto stabile. Questo la rende molto facile da stringere e si adatta perfettamente a voi e al vostro bambino. Tra l'altro, il lino proviene da coltivazioni biologiche controllate.\r\n\r\nL'etichetta cucita \u00e8 certificata e realizzata in poliestere riciclato. L'ecopelle e l'etichetta sono quindi un compromesso che dobbiamo accettare. Se avete un suggerimento per un'alternativa, fatecelo sapere.\r\n\r\n\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1092894267\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t\n  \n    <div class=\"row large-columns-1 medium-columns- small-columns- row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 2000}' >\n\n  \n\t     <div class=\"product-small col has-hover product type-product post-11983 status-publish first instock product_cat-fascia-porta-bebe-in-cotone-imbragature product_cat-tessuti-di-cotone product_tag-cotone product_tag-elephant-it product_tag-fascia-porta-bebe product_tag-nero product_tag-verde has-post-thumbnail sale featured purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">In offerta!<\/span><\/div><\/div>\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-fascia-porta-bebe-nero-verde-in-cotone\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-tragetuch-aus-baumwolle-elefanten-baby-richtig-gebunden-247x247.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"nero-verde-cotone-fionda-elefante-bambino-adeguatamente-legato\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-tragetuch-aus-baumwolle-elefanten-baby-richtig-gebunden-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-tragetuch-aus-baumwolle-elefanten-baby-richtig-gebunden-100x100.jpg 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-tragetuch-aus-baumwolle-elefanten-baby-richtig-gebunden-150x150.jpg 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-edles-tragetuch-aus-baumwolle-elefanten-247x247.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"nero-verde-nobile-cotone-fionda-elefanti\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-edles-tragetuch-aus-baumwolle-elefanten-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-edles-tragetuch-aus-baumwolle-elefanten-100x100.jpg 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/schwarz-gruen-edles-tragetuch-aus-baumwolle-elefanten-150x150.jpg 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"11983\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tImbragature in cotone\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-fascia-porta-bebe-nero-verde-in-cotone\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Elephant &#8211; Imbragature<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,70&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi>164,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-11951 status-publish instock product_cat-fascia-porta-bebe-in-cotone-imbragature product_cat-tessuti-di-cotone product_tag-cotone product_tag-elephant-it product_tag-fascia-porta-bebe product_tag-nero product_tag-rosa-it-2 has-post-thumbnail sale purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">In offerta!<\/span><\/div><\/div>\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-nero-rosa-fascia-porta-bebe\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-baumwolle-elefant-lila-wald-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Una donna \u00e8 seduta rilassata nella foresta e indossa un marsupio viola-rosa in cotone al 100% con un grande motivo elefante.\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-baumwolle-elefant-lila-wald-247x247.webp 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-baumwolle-elefant-lila-wald-150x150.webp 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-baumwolle-elefant-lila-wald-100x100.webp 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/ring-sling-tragetuch-elefant-pink-sonnenuntergang-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La donna porta il suo bambino in una fascia rosa con motivo elefante su un prato al tramonto.\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/ring-sling-tragetuch-elefant-pink-sonnenuntergang-247x247.webp 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/ring-sling-tragetuch-elefant-pink-sonnenuntergang-150x150.webp 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/ring-sling-tragetuch-elefant-pink-sonnenuntergang-100x100.webp 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"11951\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tImbragature in cotone\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-nero-rosa-fascia-porta-bebe\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Elephant &#8211; Imbragature<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,70&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi>164,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-14591 status-publish last instock product_cat-fascia-porta-bebe-in-cotone-imbragature product_cat-tessuti-di-cotone product_tag-cotone product_tag-elephant-it product_tag-fascia-porta-bebe product_tag-nero has-post-thumbnail sale purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">In offerta!<\/span><\/div><\/div>\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-imbragature-oro-nero\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/Tragetuch-Baby-Elefant-gold-schwarz-247x247.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Baby Tragetuch mit Elefantenmotiv in gold-schwarz\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/Tragetuch-Baby-Elefant-gold-schwarz-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/Tragetuch-Baby-Elefant-gold-schwarz-150x150.jpg 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/Tragetuch-Baby-Elefant-gold-schwarz-100x100.jpg 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/elefanten-tragetuch-schwarz-gold-aus-baumwolle-247x247.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"elefanten-tragetuch-schwarz-gold-aus-baumwolle\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/elefanten-tragetuch-schwarz-gold-aus-baumwolle-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/elefanten-tragetuch-schwarz-gold-aus-baumwolle-100x100.jpg 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/elefanten-tragetuch-schwarz-gold-aus-baumwolle-150x150.jpg 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14591\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tImbragature in cotone\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-imbragature-oro-nero\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Elephant &#8211; Imbragature<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,70&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi>164,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-11802 status-publish first instock product_cat-fascia-porta-bebe-in-cotone-imbragature product_cat-tessuti-di-cotone product_tag-blanc-it product_tag-cotone product_tag-elephant-it product_tag-fascia-porta-bebe product_tag-verde has-post-thumbnail sale purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">In offerta!<\/span><\/div><\/div>\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-fascia-porta-bebe-in-cotone-bianco-verde\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-elefant-salbeigruen-binden-wald-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"La donna porta il suo bambino sulla schiena nell&#039;erba di canna autunnale. La lunga fascia verde chiaro con motivo elefante cade elegantemente come un vestito.\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-elefant-salbeigruen-binden-wald-247x247.webp 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-elefant-salbeigruen-binden-wald-150x150.webp 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/babytragetuch-elefant-salbeigruen-binden-wald-100x100.webp 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/tragetuch-baumwolle-elefant-mandala-nahaufnahme-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Primo piano di un marsupio legato in verde-bianco. Si vede una testa di elefante dettagliata e un piccolo mandala sul dorso del bambino.\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/tragetuch-baumwolle-elefant-mandala-nahaufnahme-247x247.webp 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/tragetuch-baumwolle-elefant-mandala-nahaufnahme-150x150.webp 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2022\/03\/tragetuch-baumwolle-elefant-mandala-nahaufnahme-100x100.webp 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"11802\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tImbragature in cotone\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-fascia-porta-bebe-in-cotone-bianco-verde\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Elephant &#8211; Imbragature<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,70&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi>164,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-14539 status-publish instock product_cat-fascia-porta-bebe-in-cotone-imbragature product_cat-tessuti-di-cotone product_tag-azzurro product_tag-blanc-it product_tag-cotone product_tag-elephant-it product_tag-fascia-porta-bebe has-post-thumbnail sale featured purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">In offerta!<\/span><\/div><\/div>\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-imbragature-blu\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/tragetuch-aus-baumwolle-elefanten-motiv-247x247.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"tragetuch-aus-baumwolle-elefanten-motiv\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/tragetuch-aus-baumwolle-elefanten-motiv-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/tragetuch-aus-baumwolle-elefanten-motiv-100x100.jpg 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2023\/02\/tragetuch-aus-baumwolle-elefanten-motiv-150x150.jpg 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2025\/04\/Baumwolle-Baby-Tragetuch_Elefantenmotiv-weiss-blau-247x247.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Alternative view of Elephant - Imbragature\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2025\/04\/Baumwolle-Baby-Tragetuch_Elefantenmotiv-weiss-blau-247x247.jpg 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2025\/04\/Baumwolle-Baby-Tragetuch_Elefantenmotiv-weiss-blau-150x150.jpg 150w, https:\/\/mariblum.de\/wp-content\/uploads\/2025\/04\/Baumwolle-Baby-Tragetuch_Elefantenmotiv-weiss-blau-100x100.jpg 100w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14539\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tImbragature in cotone\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/elephant-imbragature-blu\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Elephant &#8211; Imbragature<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>138,70&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi>164,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-7361 status-publish last instock product_cat-ring-sling-it product_cat-ring-sling-it-in-canapa product_cat-tessuti-di-canapa product_tag-dente-di-leone product_tag-giallo product_tag-ring-sling-it has-post-thumbnail featured purchasable product-type-variable has-default-attributes has-product-safety-information\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/mariblum.de\/it\/produkt\/dente-di-leone-ring-sling-giallo-in-canapa\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-trageberatung-247x247.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"dente-di-leone-ring-sling-giallo-in-canapa\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-trageberatung-247x247.png 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-trageberatung-100x100.png 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-trageberatung-150x150.png 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-gebunden-247x247.png\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"dente-di-leone-ring-sling-giallo-in-canapa\" aria-hidden=\"true\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-gebunden-247x247.png 247w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-gebunden-100x100.png 100w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/02\/loewenzahn-ring-sling-aus-hanf-gebunden-150x150.png 150w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"7361\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tRing Slings\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/mariblum.de\/it\/produkt\/dente-di-leone-ring-sling-giallo-in-canapa\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Dente di leone &#8211; Ring Sling in canapa<\/a><\/p><\/div><div class=\"price-wrapper\">\n\n\n\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n<\/div><\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\nI nostri pacchi e materiali di spedizione provengono da BioBiene. Si tratta di un produttore di materiale da imballaggio biologico che ci fornisce un imballaggio al 100% privo di plastica.\n<h5>Istruzioni per la cura:<\/h5>\r\n<div>\r\n<p style=\"text-align: justify;\">I tessuti in canapa adorano l\u2019acqua e non vogliono il caldo secco. Gli fai quindi un favore, se di tanto in tanto metti il tuo fascia porta beb\u00e8 in canapa in acqua limpida. Dopo puoi stirarlo quando \u00e8 ancora leggermente umido. I tessili in canapa non apprezzano il caldo secco \u2013 non metterli nell\u2019asciugatrice.<\/p>\r\n<\/div>\r\n<div><\/div>\r\n<div><\/div>\r\n<div><center><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4292\" src=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/11\/pflegehinweise-hanf-300x66.png\" alt=\"pflegehinweise f\u00fcr tragetuch aus hanf\" width=\"300\" height=\"66\" srcset=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/11\/pflegehinweise-hanf-300x66.png 300w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/11\/pflegehinweise-hanf-510x111.png 510w, https:\/\/mariblum.de\/wp-content\/uploads\/2019\/11\/pflegehinweise-hanf.png 549w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/center><\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p align=\"justify\"><em>Nobile ed emozionante<\/em>, un&#8217;attrazione nel vero senso della parola. Viola brillante e glorioso: il nostro <strong>Campo di Lavanda<\/strong><\/p>\n<ul>\r\n \t<li>100% lino (coltivata in modo biologico), delicata per la pelle di voi e del vostro bambino.<\/li>\r\n \t<li>colore derivato dalle piante \u2013 tinta per la pelle del bambino senza sostanze chimiche industriali<\/li>\r\n \t<li>Privo di sostanze chimiche industriali e coloranti sintetici<\/li>\r\n \t<li>leggero e confortevole per tutto il tempo in cui viene indossato, con un peso base di soli 190g\/m\u00b2.<\/li>\r\n \t<li>72 cm di larghezza con estremit\u00e0 diritte<\/li>\r\n<\/ul>\n","protected":false},"featured_media":19061,"template":"","meta":[],"product_brand":[],"product_cat":[897,1446,2430],"product_tag":[855,997,856,982],"class_list":["post-15036","product","type-product","status-publish","has-post-thumbnail","product_cat-ring-sling-it","product_cat-ring-sling-it-in-lino","product_cat-tessuti-di-lini","product_tag-biologica","product_tag-lilla","product_tag-lino","product_tag-ring-sling-it","first","instock","featured","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fionda ad anello in lino viola &quot;Campo di Lavanda&quot; (biologico)<\/title>\n<meta name=\"description\" content=\"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore &quot;viola&quot; e allo stesso tempo non...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo di Lavanda - Ring Sling in lino\" \/>\n<meta property=\"og:description\" content=\"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore &quot;viola&quot; e allo stesso tempo non...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/\" \/>\n<meta property=\"og:site_name\" content=\"mariblum - Fascia Porta Bebe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T12:29:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/10\/blue-linen-ring-sling-babywearing3-scaled-e1589112264598.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"534\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/\",\"url\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/\",\"name\":\"Fionda ad anello in lino viola \\\"Campo di Lavanda\\\" (biologico)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mariblum.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Lavendel-Ring-Sling-aus-Hanf.jpeg\",\"datePublished\":\"2023-04-13T14:45:49+00:00\",\"dateModified\":\"2025-04-21T12:29:17+00:00\",\"description\":\"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore \\\"viola\\\" e allo stesso tempo non...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mariblum.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Lavendel-Ring-Sling-aus-Hanf.jpeg\",\"contentUrl\":\"https:\\\/\\\/mariblum.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Lavendel-Ring-Sling-aus-Hanf.jpeg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/produkt\\\/campo-di-lavanda-ring-sling-in-lino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mariblum.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mariblum.de\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campo di Lavanda &#8211; Ring Sling in lino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/mariblum.de\\\/it\\\/\",\"name\":\"mariblum Traget\u00fccher\",\"description\":\"il modo naturale di portare il tuo bambino \",\"publisher\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mariblum.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#organization\",\"name\":\"mariblum\",\"url\":\"https:\\\/\\\/mariblum.de\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mariblum.de\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo_m-500x_transparent.png\",\"contentUrl\":\"https:\\\/\\\/mariblum.de\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo_m-500x_transparent.png\",\"width\":500,\"height\":500,\"caption\":\"mariblum\"},\"image\":{\"@id\":\"https:\\\/\\\/mariblum.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/_mariblum_\\\/\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fionda ad anello in lino viola \"Campo di Lavanda\" (biologico)","description":"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore \"viola\" e allo stesso tempo non...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/","og_locale":"it_IT","og_type":"article","og_title":"Campo di Lavanda - Ring Sling in lino","og_description":"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore \"viola\" e allo stesso tempo non...","og_url":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/","og_site_name":"mariblum - Fascia Porta Bebe","article_modified_time":"2025-04-21T12:29:17+00:00","og_image":[{"width":534,"height":800,"url":"https:\/\/mariblum.de\/wp-content\/uploads\/2019\/10\/blue-linen-ring-sling-babywearing3-scaled-e1589112264598.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/","url":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/","name":"Fionda ad anello in lino viola \"Campo di Lavanda\" (biologico)","isPartOf":{"@id":"https:\/\/mariblum.de\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/#primaryimage"},"image":{"@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/#primaryimage"},"thumbnailUrl":"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/04\/Lavendel-Ring-Sling-aus-Hanf.jpeg","datePublished":"2023-04-13T14:45:49+00:00","dateModified":"2025-04-21T12:29:17+00:00","description":"Questa bellissima fionda ad anello con campo di lavanda \u00e8 realizzata in 100% lino biologico e assomiglia alla sorella maggiore \"viola\" e allo stesso tempo non...","breadcrumb":{"@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/#primaryimage","url":"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/04\/Lavendel-Ring-Sling-aus-Hanf.jpeg","contentUrl":"https:\/\/mariblum.de\/wp-content\/uploads\/2023\/04\/Lavendel-Ring-Sling-aus-Hanf.jpeg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mariblum.de\/it\/produkt\/campo-di-lavanda-ring-sling-in-lino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mariblum.de\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mariblum.de\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Campo di Lavanda &#8211; Ring Sling in lino"}]},{"@type":"WebSite","@id":"https:\/\/mariblum.de\/it\/#website","url":"https:\/\/mariblum.de\/it\/","name":"mariblum Traget\u00fccher","description":"il modo naturale di portare il tuo bambino ","publisher":{"@id":"https:\/\/mariblum.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mariblum.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mariblum.de\/it\/#organization","name":"mariblum","url":"https:\/\/mariblum.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mariblum.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/mariblum.de\/wp-content\/uploads\/2020\/07\/logo_m-500x_transparent.png","contentUrl":"https:\/\/mariblum.de\/wp-content\/uploads\/2020\/07\/logo_m-500x_transparent.png","width":500,"height":500,"caption":"mariblum"},"image":{"@id":"https:\/\/mariblum.de\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/_mariblum_\/"]}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/product\/15036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/media\/19061"}],"wp:attachment":[{"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/media?parent=15036"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/product_brand?post=15036"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/product_cat?post=15036"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mariblum.de\/it\/wp-json\/wp\/v2\/product_tag?post=15036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}